{"id":52,"count":1,"description":"","link":"https:\/\/saudevirtual.pt\/aprendersaude\/course-tag\/ginecologia\/","name":"Ginecologia","slug":"ginecologia","taxonomy":"course-tag","meta":[],"_links":{"self":[{"href":"https:\/\/saudevirtual.pt\/aprendersaude\/wp-json\/wp\/v2\/course-tag\/52","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saudevirtual.pt\/aprendersaude\/wp-json\/wp\/v2\/course-tag"}],"about":[{"href":"https:\/\/saudevirtual.pt\/aprendersaude\/wp-json\/wp\/v2\/taxonomies\/course-tag"}],"wp:post_type":[{"href":"https:\/\/saudevirtual.pt\/aprendersaude\/wp-json\/wp\/v2\/courses?course-tag=52"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}